{"id":5471,"date":"2023-03-27T17:06:19","date_gmt":"2023-03-27T15:06:19","guid":{"rendered":"https:\/\/zanzibar.app\/?post_type=place&#038;p=5471"},"modified":"2023-03-27T17:06:43","modified_gmt":"2023-03-27T15:06:43","slug":"fahari-zanzibar","status":"publish","type":"place","link":"https:\/\/zanzibar.app\/sw-tz\/place\/fahari-zanzibar\/","title":{"rendered":"Fahari Zanzibar"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":5472,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","place-type":[150,156],"place-categories":[170],"place-amenities":[],"place-city":[164],"class_list":["post-5471","place","type-place","status-publish","has-post-thumbnail","hentry","place-type-gift-shop","place-type-luxury","place-categories-shop","place-city-stone-town"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fahari Zanzibar - Zanzibar App: Zanzibar Tourism Travel Guide<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zanzibar.app\/sw-tz\/place\/fahari-zanzibar\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fahari Zanzibar - Zanzibar App: Zanzibar Tourism Travel Guide\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zanzibar.app\/sw-tz\/place\/fahari-zanzibar\/\" \/>\n<meta property=\"og:site_name\" content=\"Zanzibar App: Zanzibar Tourism Travel Guide\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-27T15:06:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zanzibar.app\/wp-content\/uploads\/2023\/03\/fahari-zanzibar.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"469\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zanzibar.app\\\/place\\\/fahari-zanzibar\\\/\",\"url\":\"https:\\\/\\\/zanzibar.app\\\/place\\\/fahari-zanzibar\\\/\",\"name\":\"Fahari Zanzibar - Zanzibar App: Zanzibar Tourism Travel Guide\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zanzibar.app\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zanzibar.app\\\/place\\\/fahari-zanzibar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zanzibar.app\\\/place\\\/fahari-zanzibar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zanzibar.app\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/fahari-zanzibar.jpg\",\"datePublished\":\"2023-03-27T15:06:19+00:00\",\"dateModified\":\"2023-03-27T15:06:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zanzibar.app\\\/place\\\/fahari-zanzibar\\\/#breadcrumb\"},\"inLanguage\":\"sw\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zanzibar.app\\\/place\\\/fahari-zanzibar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sw\",\"@id\":\"https:\\\/\\\/zanzibar.app\\\/place\\\/fahari-zanzibar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zanzibar.app\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/fahari-zanzibar.jpg\",\"contentUrl\":\"https:\\\/\\\/zanzibar.app\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/fahari-zanzibar.jpg\",\"width\":620,\"height\":469,\"caption\":\"fahari-zanzibar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zanzibar.app\\\/place\\\/fahari-zanzibar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zanzibar.app\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Place\",\"item\":\"https:\\\/\\\/zanzibar.app\\\/place\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fahari Zanzibar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zanzibar.app\\\/#website\",\"url\":\"https:\\\/\\\/zanzibar.app\\\/\",\"name\":\"Zanzibar App: Zanzibar Tourism Travel Guide\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zanzibar.app\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sw\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fahari Zanzibar - Zanzibar App: Zanzibar Tourism Travel Guide","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zanzibar.app\/sw-tz\/place\/fahari-zanzibar\/","og_locale":"en_US","og_type":"article","og_title":"Fahari Zanzibar - Zanzibar App: Zanzibar Tourism Travel Guide","og_url":"https:\/\/zanzibar.app\/sw-tz\/place\/fahari-zanzibar\/","og_site_name":"Zanzibar App: Zanzibar Tourism Travel Guide","article_modified_time":"2023-03-27T15:06:43+00:00","og_image":[{"width":620,"height":469,"url":"https:\/\/zanzibar.app\/wp-content\/uploads\/2023\/03\/fahari-zanzibar.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zanzibar.app\/place\/fahari-zanzibar\/","url":"https:\/\/zanzibar.app\/place\/fahari-zanzibar\/","name":"Fahari Zanzibar - Zanzibar App: Zanzibar Tourism Travel Guide","isPartOf":{"@id":"https:\/\/zanzibar.app\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zanzibar.app\/place\/fahari-zanzibar\/#primaryimage"},"image":{"@id":"https:\/\/zanzibar.app\/place\/fahari-zanzibar\/#primaryimage"},"thumbnailUrl":"https:\/\/zanzibar.app\/wp-content\/uploads\/2023\/03\/fahari-zanzibar.jpg","datePublished":"2023-03-27T15:06:19+00:00","dateModified":"2023-03-27T15:06:43+00:00","breadcrumb":{"@id":"https:\/\/zanzibar.app\/place\/fahari-zanzibar\/#breadcrumb"},"inLanguage":"sw","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zanzibar.app\/place\/fahari-zanzibar\/"]}]},{"@type":"ImageObject","inLanguage":"sw","@id":"https:\/\/zanzibar.app\/place\/fahari-zanzibar\/#primaryimage","url":"https:\/\/zanzibar.app\/wp-content\/uploads\/2023\/03\/fahari-zanzibar.jpg","contentUrl":"https:\/\/zanzibar.app\/wp-content\/uploads\/2023\/03\/fahari-zanzibar.jpg","width":620,"height":469,"caption":"fahari-zanzibar"},{"@type":"BreadcrumbList","@id":"https:\/\/zanzibar.app\/place\/fahari-zanzibar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zanzibar.app\/"},{"@type":"ListItem","position":2,"name":"Place","item":"https:\/\/zanzibar.app\/place\/"},{"@type":"ListItem","position":3,"name":"Fahari Zanzibar"}]},{"@type":"WebSite","@id":"https:\/\/zanzibar.app\/#website","url":"https:\/\/zanzibar.app\/","name":"Ushauri wa Safari za Zanzibar \u2014 App ya Zanzibar: Mwongozo wa Kusafiri wa Utalii Zanzibar","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zanzibar.app\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sw"}]}},"featured_media_url":"https:\/\/zanzibar.app\/wp-content\/uploads\/2023\/03\/fahari-zanzibar.jpg","golo-place_price_short":"","golo-place_price_unit":"m","golo-place_price_range":"0","golo-place_booking_type":"","golo-place_booking":"","golo-place_booking_site":"","golo-place_booking_2":"","golo-place_booking_site_2":"","golo-place_booking_banner":{"id":"0","url":""},"golo-place_booking_banner_url":"","golo-place_booking_form":"14","golo-place_phone":"","golo-place_phone2":"","golo-place_email":"","golo-place_website":"","golo-place_identity":"5471","golo-google_review_placeid":"","golo-place_facebook":"","golo-place_instagram":"","golo-place_twitter":"","golo-additional_detail":"1","golo-additional_detail_icon":[""],"golo-additional_detail_name":[""],"golo-additional_detail_url":[""],"golo-opening_monday":"Monday","golo-opening_monday_time":"","golo-opening_tuesday":"Tuesday","golo-opening_tuesday_time":"","golo-opening_wednesday":"Wednesday","golo-opening_wednesday_time":"","golo-opening_thursday":"Thursday","golo-opening_thursday_time":"","golo-opening_friday":"Friday","golo-opening_friday_time":"","golo-opening_saturday":"Saturday","golo-opening_saturday_time":"","golo-opening_sunday":"Sunday","golo-opening_sunday_time":"","golo-yelp_review":"1","golo-yelp_review_title":[""],"golo-yelp_review_type":[""],"golo-place_views_count":"5141","golo-menu_enable":"0","golo-menu_types":"1","golo-menu_types_name":[""],"golo-menu_tab":[{"golo-menu_title":"","golo-menu_price":"","golo-menu_description":"","golo-menu_image":{"id":"0","url":""},"golo-menu_item_type":""}],"golo-place_address":"62 Kenyatta Rd, Zanzibar","golo-place_zip":"","golo-place_timezone":"Africa\/Dar_es_Salaam","golo-place_location":{"location":"-74.5, 40","address":"62 Kenyatta Rd, Zanzibar"},"golo-place_featured":"0","golo-place_logged":"0","golo-place_images":["https:\/\/zanzibar.app\/wp-content\/uploads\/2023\/03\/fahari-zanzibar.jpg"],"golo-place_video_url":"","golo-place_video_image":"","golo-faqs_enable":"0","golo-faqs_tab":[{"golo-faqs_title":"","golo-faqs_description":""}],"golo-booking_item_name":"","golo-booking_item_id":"","golo-booking_item_author":"","golo-booking_adults":"","golo-booking_childrens":"","golo-booking_date":"","golo-booking_time":"","golo-place_coupon":"","golo-package_free":"","golo-package_price":"","golo-package_unlimited_time":"","golo-package_time_unit":"","golo-package_period":"","golo-package_unlimited_listing":"","golo-package_number_listings":"","golo-package_number_featured":"","golo-package_order_display":"","golo-package_featured":"","golo-package_visible":"","golo-package_extra_featured":"","golo-place_rating":"","golo-review_count":0,"_links":{"self":[{"href":"https:\/\/zanzibar.app\/sw-tz\/wp-json\/wp\/v2\/place\/5471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zanzibar.app\/sw-tz\/wp-json\/wp\/v2\/place"}],"about":[{"href":"https:\/\/zanzibar.app\/sw-tz\/wp-json\/wp\/v2\/types\/place"}],"author":[{"embeddable":true,"href":"https:\/\/zanzibar.app\/sw-tz\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zanzibar.app\/sw-tz\/wp-json\/wp\/v2\/comments?post=5471"}],"version-history":[{"count":1,"href":"https:\/\/zanzibar.app\/sw-tz\/wp-json\/wp\/v2\/place\/5471\/revisions"}],"predecessor-version":[{"id":5473,"href":"https:\/\/zanzibar.app\/sw-tz\/wp-json\/wp\/v2\/place\/5471\/revisions\/5473"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zanzibar.app\/sw-tz\/wp-json\/wp\/v2\/media\/5472"}],"wp:attachment":[{"href":"https:\/\/zanzibar.app\/sw-tz\/wp-json\/wp\/v2\/media?parent=5471"}],"wp:term":[{"taxonomy":"place-type","embeddable":true,"href":"https:\/\/zanzibar.app\/sw-tz\/wp-json\/wp\/v2\/place-type?post=5471"},{"taxonomy":"place-categories","embeddable":true,"href":"https:\/\/zanzibar.app\/sw-tz\/wp-json\/wp\/v2\/place-categories?post=5471"},{"taxonomy":"place-amenities","embeddable":true,"href":"https:\/\/zanzibar.app\/sw-tz\/wp-json\/wp\/v2\/place-amenities?post=5471"},{"taxonomy":"place-city","embeddable":true,"href":"https:\/\/zanzibar.app\/sw-tz\/wp-json\/wp\/v2\/place-city?post=5471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}